{"id":134,"count":1,"description":"","link":"https:\/\/www.costedelsud.it\/notizie\/tag\/torri-costiere-salento","name":"torri costiere Salento","slug":"torri-costiere-salento","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/www.costedelsud.it\/notizie\/wp-json\/wp\/v2\/tags\/134","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.costedelsud.it\/notizie\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/www.costedelsud.it\/notizie\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/www.costedelsud.it\/notizie\/wp-json\/wp\/v2\/posts?tags=134"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}