{"id":1756,"date":"2019-12-26T16:33:00","date_gmt":"2019-12-26T15:33:00","guid":{"rendered":"https:\/\/www.costedelsud.it\/notizie\/?p=1756"},"modified":"2019-12-26T17:35:10","modified_gmt":"2019-12-26T16:35:10","slug":"presepi-nel-salento-calendario-2019-presepi-viventi","status":"publish","type":"post","link":"https:\/\/www.costedelsud.it\/notizie\/presepi-nel-salento-calendario-2019-presepi-viventi.html","title":{"rendered":"Presepi nel Salento Calendario 2019 Presepi Viventi"},"content":{"rendered":"<p><strong>Presepe vivente di Alliste<\/strong><br \/>\nPresepe Rupestre \u201cStella in Collina\u201d realizzato appunto sulla Collina di Alliste. Per tutto il resto dell\u2019anno, le statue realizzate dallo scultore Luigi Sicuro che popolano il presepio, rimangono comunque visibili al pubblico. Visitabile nei giorni 25, 26 Dicembre 2016 e 1, 6, 8 Gennaio 2017. Orari: dalle 18.00 alle 21.30<\/p>\n<p><strong>Presepe vivente di Caprarica<\/strong><br \/>\nSuggestivo presepe vivente che con la terza edizione sapr\u00e0 sorprendere ancora di pi\u00f9. Si svolge in una location unica, l\u2019archeodromo Kal\u00f2s di Capararica. Visitabile nei giorni 18, 25, 26, 27 Dicembre 2016 e 1, 5, 6 Gennaio 2017. Orari: dalle 17 alle 21.30.<\/p>\n<p><strong>Presepe vivente di Castro<\/strong><br \/>\n\u201cNatale in Contea\u201d, curato dal Comune di Castro in collaborazione con il \u201cGruppo Antonio\u201d, \u201cFratres\u201d, A.N.M.I., Pro Loco Castro, A.C.R. Figli di Minerva, viene realizzato nel suggestivo Borgo Medievale di Castro con figuranti in costume medievale. \u00c8 aperto al pubblico nei giorni 26 Dicembre 2016 e 1, 6 Gennaio 2017. Orari: dalle 17 alle 21.<\/p>\n<p><strong>Presepe vivente di Copertino<\/strong><br \/>\nRealizzato negli spazi del santuario di Santa Maria della Grottella, sar\u00e0 possibile visitare il cosidetto \u201cgiardino del vescovo\u201d e alcune stanze conventuali. Visitabile il 25, 26, 30 Dicembre 2016 e 1, 6 Gennaio 2017. Orari: dalle 17.00 alle 22.00<\/p>\n<p><strong>Presepe vivente di Frigole<\/strong><br \/>\nRealizzato nei pressi della chiesa Santa Maria Goretti, a cura della Pro Loco, giunge alla terza edizione e si compone di oltre 100 figuranti. Apertura al pubblico 25, 26 Dicembre 2016 e 1, 6 Gennaio 2017. Orari: dalle 17.30 alle 20.30<\/p>\n<p><strong>Presepe vivente di Galatone<\/strong><br \/>\nAllestito nel vecchio podere lungo la strada provinciale per Santa Maria al Bagno. Visitabile nei giorni 25, 26 Dicembre 2016 e 1 e 6 Gennaio 2017. Orari: dalle 17.30 alle 20.30.<\/p>\n<p><strong>Presepe vivente di Gemini (fraz. Ugento)<\/strong><br \/>\nUndicesima edizione, realizzato tra le strade ed i palazzi di Gemini. A cura dell\u2019Associazione Culturale Gemini. Apertura al pubblico 25, 26 Dicembre 2016 e 1, 6 Gennaio 2017. Orari: dalle 17.30 alle 21.00<\/p>\n<p><strong>Presepe vivente di Lecce<\/strong><br \/>\nSi tratta di un piccolo villaggio creato intorno alla chiesa di San Francesco d\u2019Assisi. Apertura al pubblico 25, 26,28, 30 Dicembre 2016 e 1, 6, 7, 8 Gennaio 2017. Orari: dalle 17.00 alle 21.00<\/p>\n<p><strong>Presepe vivente di Martano<\/strong><br \/>\nSi sviluppa lungo le tipiche stradine del centro storico della citt\u00e0, precisamente tra la parrocchia di Maria Ss. del Rosario e la parrocchia Maria Ss. Assunta. Apertura al pubblico 25, 26 Dicembre 2016 e 1, 6 Gennaio 2017. Orari: dalle 18.00 alle 21.00<\/p>\n<p><strong>Presepe vivente di Monteroni<\/strong><br \/>\nRealizzato all\u2019interno del Palazzo Baronale, in pieno centro storico. Visitabile nei giorni 26 Dicembre 2016 e 1 Gennaio 2017. Orari: dalle 18.00 alle 21.00.<\/p>\n<p><strong>Presepe vivente di Nard\u00f2<\/strong><br \/>\nRealizzato dall\u2019Associazione Pro Loco giunge alla terza edizione nel centro storico di Nard\u00f2, l\u2019intero percorso \u00e8 stato allestito all\u2019interno del Palazzo Vescovile e della Cattedrale in via Garibaldi. Aperto il 25, 26 Dicembre 2016 e 1, 6, 8 Gennaio 2017. Orari: dalle 18.00 alle 21.00<\/p>\n<p><strong>Presepe vivente di Neviano<\/strong><br \/>\nSi sviluppa all\u2019interno del centro storico e si compone di oltre 120 figuranti, impegnati a riproporre scene di vita una volta. Aperto il 25, 26 Dicembre 2016 e 1, 6 Gennaio 2017. Orari: dalle 18.00 alle 21.00<\/p>\n<p><strong>Presepe vivente di Noha (Galatina)<\/strong><br \/>\nDopo diverse edizioni nell\u2019antica Masseria Colabaldi, anche quest\u2019anno il presepe vivente sar\u00e0 ambientato nel caratteristico centro storico del paesino. Aperto il 25, 26 Dicembre 2016 e 1, 6 Gennaio 2017. Orari: dalle 16.00 alle 21.00.<\/p>\n<p><strong>Presepe vivente di Ortelle<\/strong><br \/>\nRealizzato nel centro storico e nel Palazzo Rizzelli allestito dal gruppo Ortelle in movimento. Aperto il 25, 26 Dicembre 2016 e 1, 6 Gennaio 2016. Orari: dalle 18,00 alle 21.00<\/p>\n<p><strong>Presepe vivente di Parabita<\/strong><br \/>\nRealizzato all\u2019interno della Masseria Paradiso, sar\u00e0 il presepe dei bambini, dove i protagonisti saranno i bambini della scuola dell\u2019infanzia Parabita Baby. Aperto il 17, 18, 26 Dicembre 2016 e 6 Gennaio 2017. Orari: dalle 17,30 alle 19.30<\/p>\n<p><strong>Presepe vivente di Sanarica<\/strong><br \/>\nRealizzato nella \u201cvalle\u201d carsica di Sant\u2019Angelo, quest\u2019anno giunge alla 29 esima edizione. Senz\u2019altro uno dei pi\u00f9 bei presepi viventi del Salento. Aperto nei giorni: 25, 26 Dicembre 2016 e 1, 6 Gennaio 2017. Orari: dalle 17.30 alle 20.00.<\/p>\n<p><strong>Presepe vivente di San Cesario<\/strong><br \/>\nNell\u2019antica Masseria Cervolo realizzato dall\u2019Associazione Arte e Cultura Aria Sana San Cesario. Aperto nei giorni: 25, 26 Dicembre 2016 e 1, 6 Gennaio 2017. Orari: dalle 16.00 alle 21.00<\/p>\n<p><strong>Presepe vivente di San Donato<\/strong><br \/>\nGiunge alla XXIII esima edizione, uno dei presepi pi\u00f9 caratteristici che si svolge tra la serra e il centro storico. Lungo l\u2019itinerario \u00e8 possibile acquistare prodotti tipici realizzati al momento da maestri della cucina tradizionale salentina. Aperto nei giorni: 25, 26, 27 Dicembre 2016 e 1, 2, 6 Gennaio 2016. Orari: dalle 16.30 alle 20.30<\/p>\n<p><strong>Presepe vivente di Santa Caterina (Nard\u00f2)<\/strong><br \/>\nRealizzato dalla ProLoco di Santa Caterina di Nard\u00f2 si svolge nel suggestivo boschetto di via Pietro Micca. Giunge quest\u2019anno alla 36esima edizione. Aperto nei giorni: 26, 29 Dicembre 2016 e 6, 8 Gennaio 2017. Orari: dalle 17.00 alle 20.30<\/p>\n<p><a href=\"https:\/\/www.costedelsud.it\" target=\"_blank\" rel=\"noopener noreferrer\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-1043 size-full\" src=\"https:\/\/www.costedelsud.it\/notizie\/wp-content\/uploads\/2019\/09\/banner-offerte-salento-last-minute.jpg\" alt=\"Offerte Coste del Sud\" width=\"1000\" height=\"194\" srcset=\"https:\/\/www.costedelsud.it\/notizie\/wp-content\/uploads\/2019\/09\/banner-offerte-salento-last-minute.jpg 1000w, https:\/\/www.costedelsud.it\/notizie\/wp-content\/uploads\/2019\/09\/banner-offerte-salento-last-minute-300x58.jpg 300w, https:\/\/www.costedelsud.it\/notizie\/wp-content\/uploads\/2019\/09\/banner-offerte-salento-last-minute-768x149.jpg 768w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" \/><\/a><br \/>\n<a href=\"https:\/\/www.costedelsud.it\/\" rel=\"noopener noreferrer\"><button class=\"btn btn-primary btn-block\" type=\"button\"><b>Prenota per tempo la tua vacanza in Salento<\/b><\/button><\/a><\/p>\n<p><strong>Presepe vivente di Specchia<\/strong><br \/>\nRealizzato nel bellissimo e caratteristico centro storico medievale, si compone di 250 figuranti, il tutto curato dall\u2019associazione \u201cEugenia Ravasco\u201d Onlus, dal Comune di Specchia e dalla parrocchia della Presentazione della Vergine Maria e altre associazioni cittadine. Visitabile nei giorni 25, 26, 30 Dicembre 2016 e 1, 6 Gennaio 2017. Orari: dalle 17.30 alle 21.00.<\/p>\n<p><strong>Presepe vivente di Squinzano e Trepuzzi<\/strong><br \/>\nQuinta edizione, realizzato sull\u2019altura della serra di Sant\u2019Elia, dove sorge il Monastero Terenzano. Aperto nei giorni: 26 Dicembre 2016 e 1, 6 Gennaio 2017 dalle 17.30 e alle 21.00.<\/p>\n<p><strong>Presepe vivente di Strud\u00e0 (Vernole)<\/strong><br \/>\nRealizzato dall\u2019Associazione Culturale \u201cNuovi Orizzonti\u201d, ogni anno pi\u00f9 grande con tante novit\u00e0, giunto alla 19 esima edizione. Aperto nei giorni: 25, 26, 29 Dicembre 2016 e 1, 6, 8 Gennaio 2017. Orari: dalle 17.00 alle 20.30<\/p>\n<p><strong>Presepe vivente di Taurisano<\/strong><br \/>\nGiunge alla Decima edizione e viene realizzato nel centro storico dai giovani ragazzi dai 14 ai 30 anni delle quattro Comunit\u00e0 parrocchiali di Taurisano. Qua e l\u00e0 i centurioni romani in armature vigilano sugli abitanti della Betlemme salentina mentre Erode si compiace della bellezza delle sue odalische inghirlandate. Visitabile nei giorni 25, 26 Dicembre 2016 e 1, 6 Gennaio 2017 dalle 17.30 alle 21.00.<\/p>\n<p><strong>Presepe vivente di Torrepaduli (Fraz. Ruffano)<\/strong><br \/>\nRealizzato all\u2019interno del Palazzo Pasanisi dall\u2019Associazione anziani \u201cEttore Pasanisi\u201d, si affiancano ai giovani del paese, conta circa 70 figuranti in costumi d\u2019epoca. Aperto nei giorni: 25, 26 Dicembre 2016 e 1, 6 Gennaio 2017. Orari: dalle 17.00 alle 21.00.<\/p>\n<p><strong>Presepe vivente di Tricase<\/strong><br \/>\nGiunto alla 27esima edizione, si sviluppa sul monte Orco, ed \u00e8 considerato uno dei presepi simbolo del Salento, per l\u2019estensione dell\u2019area utilizzata e soprattutto per l\u2019organizzazione che conta circa 250 figuranti. \u00c8 visitabile nei giorni 25, 26, 28, 30 Dicembre 2016 e 1, 3, 4, 6 Gennaio 2017 Orari: dalle 17.00 alle 20.30.<\/p>\n<p><strong>Presepe vivente di Vaste (Fraz. Poggiardo)<\/strong><br \/>\nSi svolge lungo le vie del centro storico e Piazza Dante. Visitabile nei giorni 25 Dicembre 2016 e 1, 6 Gennaio 2017. Orari: dalle 16.30 alle 20.00.<\/p>\n<p><strong>Presepe vivente di Veglie<\/strong><br \/>\nRitorna dopo 5 anni di assenza, si svolge lungo le vie del centro storico con ingresso da Porta Noa. Visitabile nei giorni 25, 26 Dicembre 2016 e 1, 6 Gennaio 2017. Orari: dalle 16.30 alle 20.30.<\/p>\n<p><strong>Presepe vivente di Vignacastrisi (Fraz. Ortelle)<\/strong><br \/>\nGiunto alla 12esima edizione, conta pi\u00f9 di trenta scene e circa 300 figuranti in abiti d\u2019altri tempi. Visitabile nei giorni 25, 26 Dicembre 2016 e 1, 6 Gennaio 2017. Orari: dalle 17.30 alle 21.00.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-full wp-image-1765\" src=\"https:\/\/www.costedelsud.it\/notizie\/wp-content\/uploads\/2019\/12\/900-Presepe-2016-Taurisano.jpg\" alt=\"\" width=\"899\" height=\"525\" srcset=\"https:\/\/www.costedelsud.it\/notizie\/wp-content\/uploads\/2019\/12\/900-Presepe-2016-Taurisano.jpg 899w, https:\/\/www.costedelsud.it\/notizie\/wp-content\/uploads\/2019\/12\/900-Presepe-2016-Taurisano-300x175.jpg 300w, https:\/\/www.costedelsud.it\/notizie\/wp-content\/uploads\/2019\/12\/900-Presepe-2016-Taurisano-768x448.jpg 768w\" sizes=\"auto, (max-width: 899px) 100vw, 899px\" \/><\/p>\n<p><a href=\"https:\/\/www.costedelsud.it\" target=\"_blank\" rel=\"noopener noreferrer\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-1043 size-full\" src=\"https:\/\/www.costedelsud.it\/notizie\/wp-content\/uploads\/2019\/09\/banner-offerte-salento-last-minute.jpg\" alt=\"Offerte Coste del Sud\" width=\"1000\" height=\"194\" srcset=\"https:\/\/www.costedelsud.it\/notizie\/wp-content\/uploads\/2019\/09\/banner-offerte-salento-last-minute.jpg 1000w, https:\/\/www.costedelsud.it\/notizie\/wp-content\/uploads\/2019\/09\/banner-offerte-salento-last-minute-300x58.jpg 300w, https:\/\/www.costedelsud.it\/notizie\/wp-content\/uploads\/2019\/09\/banner-offerte-salento-last-minute-768x149.jpg 768w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" \/><\/a><br \/>\n<a href=\"https:\/\/www.costedelsud.it\/\" rel=\"noopener noreferrer\"><button class=\"btn btn-primary btn-block\" type=\"button\"><b>Prenota per tempo la tua vacanza in Salento<\/b><\/button><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Presepe vivente di Alliste Presepe Rupestre \u201cStella in Collina\u201d realizzato appunto sulla Collina di Alliste. Per tutto il resto dell\u2019anno,&hellip;<\/p>\n","protected":false},"author":2,"featured_media":1764,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_seopress_robots_primary_cat":"none","_seopress_titles_title":"","_seopress_titles_desc":"","_seopress_robots_index":"","_seopress_analysis_target_kw":"","_bos_mb_destination":[],"footnotes":""},"categories":[15,27],"tags":[387,369,31,384,39,385,37],"class_list":["post-1756","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-feste-tipiche","category-festivita-natalizie","tag-eden","tag-natale-in-puglia","tag-natale-in-salento","tag-presepi-salento","tag-presepi-salento-2019","tag-presepi-viventi","tag-presepi-viventi-nel-salento"],"_links":{"self":[{"href":"https:\/\/www.costedelsud.it\/notizie\/wp-json\/wp\/v2\/posts\/1756","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.costedelsud.it\/notizie\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.costedelsud.it\/notizie\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.costedelsud.it\/notizie\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.costedelsud.it\/notizie\/wp-json\/wp\/v2\/comments?post=1756"}],"version-history":[{"count":12,"href":"https:\/\/www.costedelsud.it\/notizie\/wp-json\/wp\/v2\/posts\/1756\/revisions"}],"predecessor-version":[{"id":1788,"href":"https:\/\/www.costedelsud.it\/notizie\/wp-json\/wp\/v2\/posts\/1756\/revisions\/1788"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.costedelsud.it\/notizie\/wp-json\/wp\/v2\/media\/1764"}],"wp:attachment":[{"href":"https:\/\/www.costedelsud.it\/notizie\/wp-json\/wp\/v2\/media?parent=1756"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.costedelsud.it\/notizie\/wp-json\/wp\/v2\/categories?post=1756"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.costedelsud.it\/notizie\/wp-json\/wp\/v2\/tags?post=1756"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}